{"id":2215,"date":"2022-11-25T13:09:25","date_gmt":"2022-11-25T13:09:25","guid":{"rendered":"https:\/\/fagel.qodeinteractive.com\/?page_id=2215"},"modified":"2023-04-10T15:02:05","modified_gmt":"2023-04-10T15:02:05","slug":"contact","status":"publish","type":"page","link":"https:\/\/spiritfolk.com\/index.php\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2215\" class=\"elementor elementor-2215\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c21051 elementor-section-boxed elementor-section-height-default elementor-section-height-default qodef-elementor-back-btn-skin-default qodef-elementor-header-skin-default\" data-id=\"0c21051\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4fa2192\" data-id=\"4fa2192\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de49dfe elementor-widget elementor-widget-text-editor\" data-id=\"de49dfe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 26-03-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<h2>tell us about <br \/>your project<\/h2>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a5c976 elementor-widget elementor-widget-qi_addons_for_elementor_contact_form_7\" data-id=\"8a5c976\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_contact_form_7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-qi-contact-form-7 \">\n\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f2277-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/2215#wpcf7-f2277-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"2277\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.7.5.1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f2277-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<label> Your name\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n\n<label> Your email\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n\n<label> Subject\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span> <\/label>\n\n<label> Your message\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<br \/>\n<button class=\"wpcf7-form-control wpcf7-submit qodef-button qodef-layout--filled qodef-html--link qodef-m qodef--marquee\" type=\"submit\"><span class=\"qodef-m-text\">Folk yea. \u2732<\/span><span class=\"qodef-m-marquee\"><span class=\"qodef-m-marquee-inner\"><span>Folk yea. \u2732<\/span><span>Folk yea. \u2732<\/span><span>Folk yea. \u2732<\/span><span>Folk yea. \u2732<\/span><\/span><\/span><\/button>\n<br \/>\n<br \/>\nThis site is protected by reCAPTCHA and the Google\n    <a href=\"https:\/\/policies.google.com\/privacy\">Privacy Policy<\/a> and\n    <a href=\"https:\/\/policies.google.com\/terms\">Terms of Service<\/a> apply.<p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"59\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>tell us about your project Your name Your email Subject Your message (optional) Folk yea. \u2732Folk yea. \u2732Folk yea. \u2732Folk yea. \u2732Folk yea. \u2732 &#916;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-full-width.php","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/spiritfolk.com\/index.php\/wp-json\/wp\/v2\/pages\/2215"}],"collection":[{"href":"https:\/\/spiritfolk.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/spiritfolk.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/spiritfolk.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/spiritfolk.com\/index.php\/wp-json\/wp\/v2\/comments?post=2215"}],"version-history":[{"count":45,"href":"https:\/\/spiritfolk.com\/index.php\/wp-json\/wp\/v2\/pages\/2215\/revisions"}],"predecessor-version":[{"id":8155,"href":"https:\/\/spiritfolk.com\/index.php\/wp-json\/wp\/v2\/pages\/2215\/revisions\/8155"}],"wp:attachment":[{"href":"https:\/\/spiritfolk.com\/index.php\/wp-json\/wp\/v2\/media?parent=2215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}